{"id":982,"date":"2026-09-01T11:30:10","date_gmt":"2026-09-01T11:30:10","guid":{"rendered":"https:\/\/sonix.ai\/ai\/?p=982"},"modified":"2026-09-01T13:52:30","modified_gmt":"2026-09-01T13:52:30","slug":"transcribe-genesys-recordings-automatically","status":"publish","type":"post","link":"https:\/\/sonix.ai\/ai\/pt\/transcrever-automaticamente-as-gravacoes-do-genesys\/","title":{"rendered":"Como transcrever grava\u00e7\u00f5es do Genesys automaticamente"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">O seu centro de atendimento regista as intera\u00e7\u00f5es com os clientes, mas a sua equipa de controlo de qualidade s\u00f3 consegue analisar manualmente uma parte das chamadas, deixando informa\u00e7\u00f5es valiosas ocultas nos ficheiros de \u00e1udio. Os modernos<\/span> <a href=\"https:\/\/sonix.ai\/features\/automated-transcription\"><span style=\"font-weight: 400;\">transcri\u00e7\u00e3o autom\u00e1tica<\/span><\/a><span style=\"font-weight: 400;\"> muda essa equa\u00e7\u00e3o ao converter grava\u00e7\u00f5es de chamadas em texto pesquis\u00e1vel e analis\u00e1vel. Quer esteja a gerir requisitos de conformidade, a formar novos agentes ou a analisar conversas com clientes para identificar tend\u00eancias, a transcri\u00e7\u00e3o autom\u00e1tica pode reduzir o tempo que as equipas gastam a ouvir as grava\u00e7\u00f5es antes de poderem agir com base nelas.<\/span><\/p>\n<h2><b>Principais conclus\u00f5es<\/b><\/h2>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">O Genesys Cloud suporta tr\u00eas op\u00e7\u00f5es de motores de transcri\u00e7\u00e3o: Transcri\u00e7\u00e3o de Voz Nativa, Servi\u00e7os de Transcri\u00e7\u00e3o de Voz Alargados e Conector de Transcri\u00e7\u00e3o para fornecedores externos<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">O modo de baixa lat\u00eancia pode reduzir a lat\u00eancia prevista das transcri\u00e7\u00f5es de aproximadamente 35-40 segundos para 3-5 segundos, sem custos adicionais<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A gest\u00e3o de dicion\u00e1rios pode melhorar o reconhecimento de terminologia espec\u00edfica da empresa, como nomes de marcas e termos do setor<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Os servi\u00e7os de transcri\u00e7\u00e3o \u00abNative\u00bb e \u00abExtended\u00bb est\u00e3o sujeitos \u00e0s quotas de utiliza\u00e7\u00e3o do Genesys fair, sendo aplicadas taxas de excedente quando uma organiza\u00e7\u00e3o ultrapassa a sua quota<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A an\u00e1lise de voz e de texto permite analisar intera\u00e7\u00f5es eleg\u00edveis em grande escala, em vez de depender apenas de chamadas selecionadas manualmente<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">As plataformas de transcri\u00e7\u00e3o externas podem complementar as funcionalidades nativas do Genesys no que diz respeito a fluxos de trabalho p\u00f3s-chamada e especializados<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">As transcri\u00e7\u00f5es de voz da Genesys permitem identificar participantes, tais como clientes, agentes, IVR, ACD, confer\u00eancias e mensagens de vozail<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">A transcri\u00e7\u00e3o automatizada transforma conversas gravadas em texto pesquis\u00e1vel, que as equipas podem analisar de forma mais eficiente<\/span><\/li>\n<\/ul>\n<h2><b>Por que raz\u00e3o a transcri\u00e7\u00e3o automatizada \u00e9 essencial para as grava\u00e7\u00f5es de chamadas da Genesys<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">A transcri\u00e7\u00e3o manual de chamadas gravadas \u00e9 um processo trabalhoso, uma vez que os revisores t\u00eam de ouvir, digitar, corrigir erros e identificar quem est\u00e1 a falar. Se multiplicarmos isso pelos grandes volumes de chamadas de um centro de atendimento, a transcri\u00e7\u00e3o pode rapidamente tornar-se um estrangulamento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A transcri\u00e7\u00e3o automatizada altera este fluxo de trabalho. Quando devidamente configurado, o Genesys Cloud converte as intera\u00e7\u00f5es de voz em texto separado por interlocutor, com informa\u00e7\u00f5es temporais e an\u00e1lise de sentimentos. Esta transforma\u00e7\u00e3o traz v\u00e1rias vantagens operacionais:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Monitoriza\u00e7\u00e3o da conformidade em grande escala<\/b><span style=\"font-weight: 400;\">: Pesquisar e analisar mais intera\u00e7\u00f5es para identificar requisitos de divulga\u00e7\u00e3o e outras express\u00f5es relacionadas com a conformidade<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Precis\u00e3o no acompanhamento dos agentes<\/b><span style=\"font-weight: 400;\">: Pesquisar nas transcri\u00e7\u00f5es frases espec\u00edficas, obje\u00e7\u00f5es ou padr\u00f5es de resposta em volumes de intera\u00e7\u00e3o mais amplos<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Extra\u00e7\u00e3o de informa\u00e7\u00f5es sobre os clientes<\/b><span style=\"font-weight: 400;\">: Identificar temas recorrentes e tend\u00eancias de opini\u00e3o sem ter de ouvir manualmente todas as grava\u00e7\u00f5es<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Rapidez na resolu\u00e7\u00e3o de lit\u00edgios<\/b><span style=\"font-weight: 400;\">: Pesquise na transcri\u00e7\u00e3o e utilize os marcadores temporais para localizar mais rapidamente os momentos relevantes da conversa<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Para os centros de atendimento que lidam com conversas confidenciais \u2014 tais como as relacionadas com cuidados de sa\u00fade, servi\u00e7os financeiros ou atendimento jur\u00eddico inicial \u2014, a transcri\u00e7\u00e3o permite criar um registo pesquis\u00e1vel que apoia os fluxos de trabalho de revis\u00e3o. As organiza\u00e7\u00f5es continuam a ter de configurar a grava\u00e7\u00e3o, o acesso, a expurga\u00e7\u00e3o, a conserva\u00e7\u00e3o e outros controlos de acordo com os seus pr\u00f3prios requisitos legais e regulamentares.<\/span><\/p>\n<h2><b>Escolher o m\u00e9todo de transcri\u00e7\u00e3o adequado para as grava\u00e7\u00f5es da Genesys<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">O Genesys Cloud suporta tr\u00eas percursos do motor de transcri\u00e7\u00e3o, sujeitos a licenciamento e configura\u00e7\u00e3o:<\/span><\/p>\n<h3><b>Transcri\u00e7\u00e3o de voz nativa do Genesys Cloud<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">A Transcri\u00e7\u00e3o de Voz do Genesys Cloud \u00e9 o motor de transcri\u00e7\u00e3o predefinido da plataforma, desde que a transcri\u00e7\u00e3o de voz esteja dispon\u00edvel ao abrigo da sua licen\u00e7a e configura\u00e7\u00e3o do Genesys. Foi concebida especificamente para conversas em centros de contacto e suporta a gest\u00e3o de dicion\u00e1rios para terminologia espec\u00edfica da organiza\u00e7\u00e3o.<\/span><\/p>\n<h3><b>Servi\u00e7os Alargados de Transcri\u00e7\u00e3o de Voz (EVTS)<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O EVTS utiliza o Amazon Transcribe para oferecer suporte adicional a idiomas e dialetos, para al\u00e9m do motor nativo da Genesys. Opte por esta op\u00e7\u00e3o quando o dialeto pretendido for suportado pelo EVTS, mas n\u00e3o pela transcri\u00e7\u00e3o de voz nativa, ou quando pretender um motor alternativo compat\u00edvel para um idioma espec\u00edfico.<\/span><\/p>\n<h3><b>Conector de transcri\u00e7\u00e3o<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O Transcription Connector permite que o Genesys Cloud transmita intera\u00e7\u00f5es de voz para um prestador de servi\u00e7os de transcri\u00e7\u00e3o externo compat\u00edvel, utilizando o protocolo AudioHook. As organiza\u00e7\u00f5es que necessitem de um prestador de servi\u00e7os preferencial, de um especialista em transcri\u00e7\u00e3o de nicho ou de um modelo lingu\u00edstico personalizado podem explorar esta op\u00e7\u00e3o. A Genesys cobra a utiliza\u00e7\u00e3o do Transcription Connector por minuto, e o prestador de servi\u00e7os externo pode ter a sua pr\u00f3pria tabela de pre\u00e7os.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A sua escolha depende de v\u00e1rios fatores:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Requisitos lingu\u00edsticos<\/b><span style=\"font-weight: 400;\"> \u2013 O Native Voice Transcription suporta um conjunto definido de l\u00ednguas e dialetos, enquanto o EVTS alarga essa cobertura<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Considera\u00e7\u00f5es relativas ao volume<\/b><span style=\"font-weight: 400;\"> \u2013 A transcri\u00e7\u00e3o nativa e a transcri\u00e7\u00e3o alargada est\u00e3o sujeitas \u00e0s dota\u00e7\u00f5es destinadas \u00e0 utiliza\u00e7\u00e3o do fair<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Necessidades de personaliza\u00e7\u00e3o<\/b><span style=\"font-weight: 400;\"> \u2013 Os diferentes motores oferecem vocabul\u00e1rios e op\u00e7\u00f5es de personaliza\u00e7\u00e3o diferentes<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Restri\u00e7\u00f5es or\u00e7amentais aints<\/b><span style=\"font-weight: 400;\"> \u2013 O Transcription Connector introduz custos adicionais de utiliza\u00e7\u00e3o e pode implicar custos separados de terceiros<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Para equipas que necessitem de an\u00e1lises p\u00f3s-plant\u00e3o, fluxos de trabalho de arquivo ou <\/span><a href=\"https:\/\/sonix.ai\/features\/automated-translation\"><span style=\"font-weight: 400;\">tradu\u00e7\u00e3o multilingue<\/span><\/a><span style=\"font-weight: 400;\">, as plataformas de transcri\u00e7\u00e3o externas podem complementar as funcionalidades nativas do Genesys, em vez de as substituir.<\/span><\/p>\n<h2><b>Transcreva sem complica\u00e7\u00f5es as grava\u00e7\u00f5es do Genesys com software de convers\u00e3o de voz em texto baseado em IA<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">A configura\u00e7\u00e3o da transcri\u00e7\u00e3o autom\u00e1tica no Genesys Cloud envolve v\u00e1rias defini\u00e7\u00f5es relativas \u00e0 organiza\u00e7\u00e3o, \u00e0 fila, ao fluxo, ao idioma e, opcionalmente, ao motor de transcri\u00e7\u00e3o.<\/span><\/p>\n<h3><b>Passos para a configura\u00e7\u00e3o inicial<\/b><\/h3>\n<p><b>Ativar transcri\u00e7\u00e3o de voz<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Aceda a Menu &gt; Intelig\u00eancia de Conversa\u00e7\u00e3o &gt; An\u00e1lise de Voz e Texto &gt; Configura\u00e7\u00e3o de Voz e Texto. No separador \u201cDefini\u00e7\u00f5es\u201d, na sec\u00e7\u00e3o \u00abTranscri\u00e7\u00e3o de voz\u00bb, selecione \u00abAtivado com base na configura\u00e7\u00e3o da fila ou na a\u00e7\u00e3o do fluxo\u00bb. Tamb\u00e9m pode ativar a Transcri\u00e7\u00e3o de Baixa Lat\u00eancia, que, segundo a Genesys, reduz a lat\u00eancia esperada da transcri\u00e7\u00e3o da API de Notifica\u00e7\u00e3o de aproximadamente 35-40 segundos para 3-5 segundos, sem custos adicionais.<\/span><\/p>\n<p><b>Configurar a transcri\u00e7\u00e3o baseada em filas<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Ative a transcri\u00e7\u00e3o de voz para as filas que a necessitem. A transcri\u00e7\u00e3o de voz tem de ser primeiro ativada para a organiza\u00e7\u00e3o. Dependendo do fluxo de chamadas, poder\u00e1 tamb\u00e9m ser necess\u00e1rio ativar a transcri\u00e7\u00e3o atrav\u00e9s de uma a\u00e7\u00e3o de transcri\u00e7\u00e3o do Architect.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por outro lado, verifique as defini\u00e7\u00f5es adequadas do tronco e do Architect\/idioma do suporte, para que a Genesys utilize o idioma de transcri\u00e7\u00e3o correto para a intera\u00e7\u00e3o.<\/span><\/p>\n<p><b>Configurar a gest\u00e3o do dicion\u00e1rio<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Utilize Menu &gt; Intelig\u00eancia de Conversa\u00e7\u00e3o &gt; An\u00e1lise de Fala e Texto &gt; Gest\u00e3o do Dicion\u00e1rio para adicionar termos espec\u00edficos da organiza\u00e7\u00e3o, tais como nomes de marcas, acr\u00f3nimos e terminologia do setor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No caso das entradas do Genesys Native Voice Transcription, \u00e9 poss\u00edvel adicionar alternativas \u201cSounds Like\u201d e frases de exemplo para melhorar o reconhecimento. As entradas do dicion\u00e1rio do EVTS utilizam campos diferentes e n\u00e3o suportam as mesmas op\u00e7\u00f5es \u00abSounds Like\u00bb e de frases de exemplo.<\/span><\/p>\n<h3><b>Desafios comuns na configura\u00e7\u00e3o<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">V\u00e1rios fatores podem afetar as configura\u00e7\u00f5es iniciais:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Transcri\u00e7\u00f5es em falta<\/b><span style=\"font-weight: 400;\"> \u2013 Certifique-se de que os requisitos relativos \u00e0 organiza\u00e7\u00e3o, fila ou fluxo, licenciamento e grava\u00e7\u00e3o para a sua configura\u00e7\u00e3o de telefonia est\u00e3o cumpridos. A Genesys exige que a grava\u00e7\u00e3o esteja ativada para as configura\u00e7\u00f5es aplic\u00e1veis<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Sa\u00edda no idioma errado<\/b><span style=\"font-weight: 400;\"> \u2013 Verifique a l\u00edngua principal relevante e a l\u00edngua suportada configuradas no Architect<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Lacunas no IVR\/nas filas de espera<\/b><span style=\"font-weight: 400;\"> \u2013 Se estiver configurada a supress\u00e3o de grava\u00e7\u00e3o ou transcri\u00e7\u00e3o para os segmentos IVR, espera ou fila-wait, essas partes n\u00e3o aparecer\u00e3o na transcri\u00e7\u00e3o<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Pausa segura<\/b><span style=\"font-weight: 400;\"> \u2013 A Genesys recomenda a utiliza\u00e7\u00e3o do \u00abSecure Pause\u00bb ou dos \u00abSecure Call Flows\u00bb para impedir que os dados PCI sejam capturados e transcritos durante as partes sens\u00edveis de uma intera\u00e7\u00e3o<\/span><\/li>\n<\/ul>\n<h2><b>Transcri\u00e7\u00e3o de grava\u00e7\u00f5es do Genesys com o Sonix<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Se quiser utilizar o Sonix para a transcri\u00e7\u00e3o p\u00f3s-chamada, o fluxo de trabalho \u00e9 muito simples:<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Exportar ou obter a grava\u00e7\u00e3o do Genesys<\/b><span style=\"font-weight: 400;\">: Descarregue a grava\u00e7\u00e3o da chamada do Genesys Cloud, desde que a sua conta tenha as permiss\u00f5es de acesso necess\u00e1rias para a grava\u00e7\u00e3o.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Carregue a grava\u00e7\u00e3o no Sonix<\/b><span style=\"font-weight: 400;\">: Adicione o ficheiro de \u00e1udio ou v\u00eddeo exportado \u00e0 sua conta Sonix.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Selecione o idioma falado<\/b><span style=\"font-weight: 400;\">: Escolha o idioma utilizado na grava\u00e7\u00e3o antes de iniciar a transcri\u00e7\u00e3o.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Executar transcri\u00e7\u00e3o automatizada<\/b><span style=\"font-weight: 400;\">: A Sonix processa a grava\u00e7\u00e3o e gera uma transcri\u00e7\u00e3o pesquis\u00e1vel com marcas temporais e separa\u00e7\u00e3o de interlocutores.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Revisar e editar a transcri\u00e7\u00e3o<\/b><span style=\"font-weight: 400;\">: Utilize o editor baseado no navegador para corrigir o texto, atualizar as legendas dos oradores e rever as sec\u00e7\u00f5es n\u00e3o confirmadas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Analisar ou traduzir a transcri\u00e7\u00e3o<\/b><span style=\"font-weight: 400;\">: Utilize as ferramentas de an\u00e1lise ou tradu\u00e7\u00e3o da Sonix AI se precisar de resumos, temas, an\u00e1lise de sentimentos, extra\u00e7\u00e3o de entidades ou resultados multilingues.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Exportar a transcri\u00e7\u00e3o finalizada<\/b><span style=\"font-weight: 400;\">:  Descarregue a transcri\u00e7\u00e3o num formato compat\u00edvel, como DOCX, TXT, PDF, SRT ou VTT, ou utilize a API da Sonix para obter dados de transcri\u00e7\u00e3o em JSON estruturado.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Este fluxo de trabalho \u00e9 mais adequado para o processamento p\u00f3s-chamada do que para a transcri\u00e7\u00e3o em tempo real do Genesys. O Sonix trabalha com a grava\u00e7\u00e3o exportada, permitindo que as equipas utilizem a transcri\u00e7\u00e3o para fluxos de trabalho de controlo de qualidade, forma\u00e7\u00e3o, an\u00e1lise de conformidade, investiga\u00e7\u00e3o, tradu\u00e7\u00e3o ou arquivo.<\/span><\/p>\n<h2><b>Melhorar as opera\u00e7\u00f5es dos centros de atendimento com ferramentas de transcri\u00e7\u00e3o baseadas em IA<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">A transcri\u00e7\u00e3o, por si s\u00f3, cria registos pesquis\u00e1veis. A verdadeira vantagem operacional reside no que se faz com essas transcri\u00e7\u00f5es depois de estas existirem.<\/span><\/p>\n<h3><b>Transforma\u00e7\u00e3o da Garantia de Qualidade<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O controlo de qualidade tradicional depende em grande medida da sele\u00e7\u00e3o e revis\u00e3o das intera\u00e7\u00f5es individuais por parte dos supervisores. Com a transcri\u00e7\u00e3o autom\u00e1tica, a an\u00e1lise de voz e de texto permite analisar intera\u00e7\u00f5es eleg\u00edveis em grande escala e identificar sinais nas conversas, tais como:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Detec\u00e7\u00e3o de t\u00f3picos<\/b><span style=\"font-weight: 400;\"> \u2013 Identificar intera\u00e7\u00f5es que incluam t\u00f3picos e frases configurados<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Acompanhamento do sentimento<\/b><span style=\"font-weight: 400;\"> \u2013 Identificar indicadores de sentimento positivo e negativo nas intera\u00e7\u00f5es suportadas<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Pesquisa de conversas<\/b><span style=\"font-weight: 400;\"> \u2013 Localizar palavras, frases e momentos da transcri\u00e7\u00e3o sem ter de ouvir a grava\u00e7\u00e3o na \u00edntegra<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">As avalia\u00e7\u00f5es formais de qualidade e os quadros de resultados remain fazem parte da Gest\u00e3o da Qualidade da Genesys, em vez de serem substitu\u00eddos apenas pela an\u00e1lise de transcri\u00e7\u00f5es.<\/span><\/p>\n<h3><b>Aplica\u00e7\u00f5es para o desenvolvimento de agentes<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">As transcri\u00e7\u00f5es tamb\u00e9m podem apoiar o acompanhamento e a forma\u00e7\u00e3o, ao disponibilizar aos supervisores e aos agentes exemplos pesquis\u00e1veis de conversas anteriores.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando o Genesys Agent Copilot \u00e9 configurado com gatilhos ou inten\u00e7\u00f5es adequados, pode apresentar artigos de conhecimento atribu\u00eddos durante uma intera\u00e7\u00e3o. As intera\u00e7\u00f5es de voz tamb\u00e9m podem apresentar uma transcri\u00e7\u00e3o em tempo real no Agent Copilot.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para <\/span><a href=\"https:\/\/sonix.ai\/features\/collaborate-with-teams\"><span style=\"font-weight: 400;\">colabora\u00e7\u00e3o em equipa<\/span><\/a><span style=\"font-weight: 400;\">, as bibliotecas de transcri\u00e7\u00f5es partilhadas podem reduzir o estrangulamento causado pela necessidade de \u201couvir esta chamada\u201d, que atrasa as conversas de acompanhamento e as avalia\u00e7\u00f5es de desempenho.<\/span><\/p>\n<h2><b>Aumentar a produtividade com ferramentas avan\u00e7adas de transcri\u00e7\u00e3o para chamadas da Genesys<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">A produtividade gerada pela transcri\u00e7\u00e3o pode abranger v\u00e1rios fluxos de trabalho. Uma transcri\u00e7\u00e3o pode servir de base para a revis\u00e3o de controlo de qualidade, a elabora\u00e7\u00e3o de exemplos, a documenta\u00e7\u00e3o de conformidade e a an\u00e1lise de insights dos clientes, sem que seja necess\u00e1rio que todas as partes interessadas ou\u00e7am a grava\u00e7\u00e3o na \u00edntegra.<\/span><\/p>\n<h3><b>Funcionalidades do editor que fazem a diferen\u00e7a<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Entre as ferramentas de transcri\u00e7\u00e3o eficazes podem incluir-se:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Reprodu\u00e7\u00e3o sincronizada<\/b><span style=\"font-weight: 400;\"> \u2013 Clique no texto da transcri\u00e7\u00e3o para avan\u00e7ar diretamente para o momento correspondente do \u00e1udio<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Identifica\u00e7\u00e3o de falantes ou diariza\u00e7\u00e3o<\/b><span style=\"font-weight: 400;\"> \u2013 Separar os di\u00e1logos por interlocutor para facilitar o acompanhamento das conversas<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Destaque de confian\u00e7a<\/b><span style=\"font-weight: 400;\"> \u2013 Indicadores visuais que ajudam os revisores a concentrarem-se nas palavras em rela\u00e7\u00e3o \u00e0s quais o motor de transcri\u00e7\u00e3o demonstra menor confian\u00e7a<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Procurar e substituir<\/b><span style=\"font-weight: 400;\"> \u2013 Corrigir de forma eficiente os erros de transcri\u00e7\u00e3o recorrentes<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">O editor de transcri\u00e7\u00f5es da Sonix, baseado no navegador, suporta reprodu\u00e7\u00e3o sincronizada, identifica\u00e7\u00e3o de interlocutores, indicadores de confian\u00e7a e ferramentas para corrigir o texto da transcri\u00e7\u00e3o.<\/span><\/p>\n<h3><b>Flexibilidade de exporta\u00e7\u00e3o<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Diferentes fluxos de trabalho exigem formatos diferentes. O Sonix suporta v\u00e1rias op\u00e7\u00f5es de exporta\u00e7\u00e3o, incluindo:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Documentos de texto<\/b><span style=\"font-weight: 400;\"> tais como DOCX, TXT e PDF para relat\u00f3rios e documenta\u00e7\u00e3o<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Ficheiros de legendas<\/b><span style=\"font-weight: 400;\"> tais como SRT e VTT para legendagem de v\u00eddeos<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Dados de transcri\u00e7\u00e3o estruturados<\/b><span style=\"font-weight: 400;\"> em formato JSON atrav\u00e9s da API da Sonix para integra\u00e7\u00f5es e fluxos de trabalho de an\u00e1lise<\/span><\/li>\n<\/ul>\n<h2><b>Garantir a seguran\u00e7a dos dados e a conformidade das transcri\u00e7\u00f5es das chamadas da Genesys<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">As grava\u00e7\u00f5es de chamadas podem conter informa\u00e7\u00f5es confidenciais, tais como detalhes de pagamento, informa\u00e7\u00f5es de sa\u00fade, discuss\u00f5es jur\u00eddicas e identificadores pessoais. Os requisitos de seguran\u00e7a para a transcri\u00e7\u00e3o devem, por conseguinte, ser considerados a par das medidas de prote\u00e7\u00e3o aplic\u00e1veis ao \u00e1udio subjacente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A Genesys encripta as transcri\u00e7\u00f5es de voz e as intera\u00e7\u00f5es gravadas e aplica o mesmo tipo de encripta\u00e7\u00e3o a ambas. Os controlos relevantes da Genesys incluem:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Oculta\u00e7\u00e3o de dados sens\u00edveis<\/b><span style=\"font-weight: 400;\"> \u2013 A Genesys pode ocultar automaticamente as entidades PCI e PII suportadas nas grava\u00e7\u00f5es e transcri\u00e7\u00f5es de voz quando as defini\u00e7\u00f5es de oculta\u00e7\u00e3o adequadas estiverem ativadas<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Acesso restrito a dados sens\u00edveis<\/b><span style=\"font-weight: 400;\"> \u2013 A permiss\u00e3o \u00abGrava\u00e7\u00e3o &gt; Grava\u00e7\u00e3o &gt; Ver Dados Sens\u00edveis\u00bb controla o acesso a conte\u00fados sens\u00edveis n\u00e3o enmascarados<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Controlos de acesso ao n\u00edvel do segmento<\/b><span style=\"font-weight: 400;\"> \u2013 Os controlos de acesso aos segmentos de grava\u00e7\u00e3o podem restringir as partes da transcri\u00e7\u00e3o que um utilizador pode visualizar<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Processamento seguro de pagamentos<\/b><span style=\"font-weight: 400;\"> \u2013 A Genesys recomenda o \u00abSecure Pause\u00bb ou os \u00abSecure Call Flows\u00bb como primeira linha de defesa para impedir que as informa\u00e7\u00f5es PCI sejam gravadas ou transcritas<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Para organiza\u00e7\u00f5es com requisitos de seguran\u00e7a adicionais,<\/span> <a href=\"https:\/\/sonix.ai\/security\"><span style=\"font-weight: 400;\">Seguran\u00e7a empresarial da Sonix<\/span><\/a><span style=\"font-weight: 400;\"> inclui a certifica\u00e7\u00e3o SOC 2 Tipo II, encripta\u00e7\u00e3o em tr\u00e2nsito e em repouso, permiss\u00f5es granulares e suporte a SSO\/SAML nos planos Enterprise.<\/span><\/p>\n<h2><b>Para al\u00e9m da transcri\u00e7\u00e3o: tirar partido da an\u00e1lise por IA para o Genesys Insights<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">As transcri\u00e7\u00f5es de texto permitem uma camada adicional de processamento capaz de extrair informa\u00e7\u00f5es \u00fateis dos dados das conversas. O Genesys Speech and Text Analytics oferece funcionalidades como t\u00f3picos, indicadores de sentimento, transcri\u00e7\u00f5es pesquis\u00e1veis e resumos de intera\u00e7\u00f5es gerados por IA.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Detec\u00e7\u00e3o de temas e t\u00f3picos: <\/b><span style=\"font-weight: 400;\">Os t\u00f3picos e frases configurados podem ajudar as equipas a identificar assuntos recorrentes em grandes conjuntos de conversas, tais como men\u00e7\u00f5es a produtos, processos ou preocupa\u00e7\u00f5es recorrentes dos clientes.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>An\u00e1lise de sentimentos: <\/b><span style=\"font-weight: 400;\">O Genesys ativa automaticamente a an\u00e1lise de sentimentos atrav\u00e9s da transcri\u00e7\u00e3o de voz e pode apresentar indicadores de sentimentos positivos e negativos nas intera\u00e7\u00f5es suportadas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Resumos das intera\u00e7\u00f5es com IA: <\/b><span style=\"font-weight: 400;\">A funcionalidade \u00abAI Insights\u00bb da Genesys pode fornecer um resumo da intera\u00e7\u00e3o, juntamente com informa\u00e7\u00f5es da transcri\u00e7\u00e3o, para as configura\u00e7\u00f5es suportadas.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Para equipas que precisam de uma an\u00e1lise mais aprofundada<\/span> <a href=\"https:\/\/sonix.ai\/features\/ai-analysis\"><span style=\"font-weight: 400;\">An\u00e1lise de IA<\/span><\/a><span style=\"font-weight: 400;\">, O Sonix suporta resumos gerados por IA, temas, an\u00e1lise de sentimentos, dete\u00e7\u00e3o de t\u00f3picos, extra\u00e7\u00e3o de entidades, cap\u00edtulos, prompts personalizados e an\u00e1lise de v\u00e1rios ficheiros.<\/span><\/p>\n<h2><b>A escolha inteligente para a transcri\u00e7\u00e3o de grava\u00e7\u00f5es da Genesys<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Embora o Genesys Cloud ofere\u00e7a funcionalidades nativas de transcri\u00e7\u00e3o e an\u00e1lise de conversas, as plataformas especializadas podem complementar a infraestrutura existente de um centro de atendimento no que diz respeito aos fluxos de trabalho p\u00f3s-chamada.<\/span><a href=\"https:\/\/sonix.ai\/\"> <span style=\"font-weight: 400;\">Sonix<\/span><\/a><span style=\"font-weight: 400;\"> fornece ferramentas para equipas que processam \u00e1udio e v\u00eddeo gravados, incluindo:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Transcri\u00e7\u00e3o e tradu\u00e7\u00e3o<\/b><span style=\"font-weight: 400;\"> \u2013 Transcri\u00e7\u00e3o autom\u00e1tica em mais de 54 idiomas e tradu\u00e7\u00e3o para mais de 55 idiomas<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Dicion\u00e1rio personalizado<\/b><span style=\"font-weight: 400;\"> \u2013  Ajuda a melhorar o reconhecimento de terminologia especializada, nomes pr\u00f3prios e linguagem espec\u00edfica da organiza\u00e7\u00e3o<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Edi\u00e7\u00e3o no navegador<\/b><span style=\"font-weight: 400;\"> \u2013 Permite que as equipas revejam e corrijam transcri\u00e7\u00f5es sem terem de instalar software no computador<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>An\u00e1lise de IA<\/b><span style=\"font-weight: 400;\"> \u2013 Suporta fluxos de trabalho de an\u00e1lise p\u00f3s-chamada, tais como resumos, temas, sentimentos e outras informa\u00e7\u00f5es extra\u00eddas das transcri\u00e7\u00f5es<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Colabora\u00e7\u00e3o em equipa<\/b><span style=\"font-weight: 400;\"> \u2013 Inclui pastas partilhadas, partilha de transcri\u00e7\u00f5es, notas e controlos de permiss\u00e3o para fluxos de trabalho com v\u00e1rios utilizadores<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Exporta\u00e7\u00f5es flex\u00edveis<\/b><span style=\"font-weight: 400;\"> \u2013 Suporta formatos como DOCX, TXT, PDF, SRT e VTT, enquanto a API da Sonix fornece dados de transcri\u00e7\u00e3o em JSON para fluxos de trabalho estruturados<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Fluxos de trabalho da Genesys ap\u00f3s as chamadas<\/b><span style=\"font-weight: 400;\"> \u2013 As grava\u00e7\u00f5es exportadas do Genesys podem ser processadas no Sonix para fluxos de trabalho de transcri\u00e7\u00e3o, tradu\u00e7\u00e3o, edi\u00e7\u00e3o, an\u00e1lise e arquivo<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Seguran\u00e7a empresarial<\/b><span style=\"font-weight: 400;\"> \u2013 A Sonix possui certifica\u00e7\u00e3o SOC 2 Tipo II, encripta os dados em tr\u00e2nsito e em repouso e suporta SSO\/SAML nos planos Enterprise<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Est\u00e1 pronto para transformar as grava\u00e7\u00f5es do Genesys em transcri\u00e7\u00f5es pesquis\u00e1veis e edit\u00e1veis? <\/span><a href=\"https:\/\/sonix.ai\/\"><span style=\"font-weight: 400;\">Experimente o Sonix<\/span><\/a><span style=\"font-weight: 400;\"> para transcrever, rever, analisar e exportar as grava\u00e7\u00f5es das suas chamadas num \u00fanico fluxo de trabalho.<\/span><\/p>\n<h2><b>Perguntas frequentes<\/b><\/h2>\n<h3><b>Quanto tempo demora o Genesys Cloud a transcrever uma grava\u00e7\u00e3o de chamada?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">No caso do Genesys Cloud Voice e do BYOC Cloud, a transcri\u00e7\u00e3o ocorre quase em tempo real. Quando a \u00abTranscri\u00e7\u00e3o de Baixa Lat\u00eancia\u00bb est\u00e1 ativada, a Genesys regista uma lat\u00eancia prevista da API de Notifica\u00e7\u00e3o de aproximadamente 3 a 5 segundos, em compara\u00e7\u00e3o com 35 a 40 segundos sem essa configura\u00e7\u00e3o. A Genesys afirma ainda que a transcri\u00e7\u00e3o completa da intera\u00e7\u00e3o fica normalmente dispon\u00edvel pouco depois do fim da intera\u00e7\u00e3o, embora a disponibilidade efetiva possa variar consoante a configura\u00e7\u00e3o e as condi\u00e7\u00f5es de processamento.<\/span><\/p>\n<h3><b>Que idiomas suporta o servi\u00e7o de transcri\u00e7\u00e3o da Genesys?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">A transcri\u00e7\u00e3o de voz nativa do Genesys Cloud suporta um conjunto definido de idiomas e dialetos regionais, em vez de mais de 30 idiomas. Os Servi\u00e7os Alargados de Transcri\u00e7\u00e3o de Voz oferecem uma cobertura mais ampla de idiomas e dialetos atrav\u00e9s do Amazon Transcribe. Uma vez que o suporte varia consoante o motor e pode sofrer altera\u00e7\u00f5es, consulte a matriz atual de idiomas suportados pelo Genesys Cloud antes da implementa\u00e7\u00e3o.<\/span><\/p>\n<h3><b>Posso transcrever grava\u00e7\u00f5es hist\u00f3ricas do Genesys que foram feitas antes de ativar a fun\u00e7\u00e3o de transcri\u00e7\u00e3o?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O fluxo de trabalho de transcri\u00e7\u00e3o de voz documentado pela Genesys foi concebido para intera\u00e7\u00f5es configuradas para transcri\u00e7\u00e3o. Se tiver grava\u00e7\u00f5es mais antigas da Genesys que ainda n\u00e3o tenham transcri\u00e7\u00f5es, uma op\u00e7\u00e3o pr\u00e1tica \u00e9 exportar o ficheiro de \u00e1udio com a extens\u00e3o available e process\u00e1-lo atrav\u00e9s de um <\/span><a href=\"https:\/\/sonix.ai\/audio-transcription\"><span style=\"font-weight: 400;\">servi\u00e7o externo de transcri\u00e7\u00e3o<\/span><\/a><span style=\"font-weight: 400;\">, sujeito aos requisitos da sua organiza\u00e7\u00e3o em mat\u00e9ria de acesso \u00e0s grava\u00e7\u00f5es, conserva\u00e7\u00e3o, privacidade e conformidade.<\/span><\/p>\n<h3><b>O que acontece se eu exceder a quota de utiliza\u00e7\u00e3o do fair para transcri\u00e7\u00e3o?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">A Genesys calcula as aloca\u00e7\u00f5es de utiliza\u00e7\u00e3o da transcri\u00e7\u00e3o de voz fair para a organiza\u00e7\u00e3o com base no n\u00famero e no tipo de licen\u00e7as fatur\u00e1veis, e essa aloca\u00e7\u00e3o pode ser utilizada tanto na Transcri\u00e7\u00e3o de Voz Nativa como na Transcri\u00e7\u00e3o de Voz Alargada. Se a organiza\u00e7\u00e3o exceder a sua aloca\u00e7\u00e3o agregada, a Genesys fatura a utiliza\u00e7\u00e3o acima dessa aloca\u00e7\u00e3o numa base por minuto. Os administradores podem monitorizar a utiliza\u00e7\u00e3o atrav\u00e9s do Genesys Billing &amp; Usage.<\/span><\/p>\n<h3><b>A transcri\u00e7\u00e3o em tempo real \u00e9 compat\u00edvel com as implementa\u00e7\u00f5es BYOC Premises?<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">N\u00e3o atrav\u00e9s do fluxo de trabalho padr\u00e3o de transcri\u00e7\u00e3o de voz \u00abNative\u00bb ou \u00abExtended\u00bb. A Genesys afirma que, com o BYOC Premises, a grava\u00e7\u00e3o conclu\u00edda \u00e9 carregada antes do in\u00edcio da transcri\u00e7\u00e3o, pelo que os casos de utiliza\u00e7\u00e3o em tempo real n\u00e3o s\u00e3o suportados por essa configura\u00e7\u00e3o. O tempo de processamento depende da dura\u00e7\u00e3o da intera\u00e7\u00e3o e, normalmente, demora cerca de metade da dura\u00e7\u00e3o da grava\u00e7\u00e3o \u2014 por exemplo, uma intera\u00e7\u00e3o completa de 10 minutos pode demorar cerca de cinco minutos a ser transcrita ap\u00f3s o seu envio.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Your contact center records customer interactions, but your QA team can manually review only a subset of calls, leaving valuable insights buried in audio files. Modern automated transcription changes that equation by converting call recordings into searchable, analyzable text. Whether you&#8217;re managing compliance requirements, training new agents, or mining customer conversations for trends, automatic transcription [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How To Transcribe Genesys Recordings Automatically - Moving AI Forward<\/title>\n<meta name=\"description\" content=\"Learn how to transcribe Genesys recordings automatically with AI. Explore native Genesys tools, Sonix, setup steps, AI analysis, security, and integrations.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sonix.ai\/ai\/pt\/transcrever-automaticamente-as-gravacoes-do-genesys\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How To Transcribe Genesys Recordings Automatically - Moving AI Forward\" \/>\n<meta property=\"og:description\" content=\"Learn how to transcribe Genesys recordings automatically with AI. Explore native Genesys tools, Sonix, setup steps, AI analysis, security, and integrations.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sonix.ai\/ai\/pt\/transcrever-automaticamente-as-gravacoes-do-genesys\/\" \/>\n<meta property=\"og:site_name\" content=\"Moving AI Forward\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/trysonix\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T11:30:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T13:52:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sonix.ai\/ai\/wp-content\/uploads\/2026\/09\/How-To-Transcribe-Genesys-Recordings-Automatically-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Nguyen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@trysonix\" \/>\n<meta name=\"twitter:site\" content=\"@trysonix\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Nguyen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/\"},\"author\":{\"name\":\"David Nguyen\",\"@id\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/#\\\/schema\\\/person\\\/7508f0c221b1e91520f0bf82e8f2ff37\"},\"headline\":\"How To Transcribe Genesys Recordings Automatically\",\"datePublished\":\"2026-09-01T11:30:10+00:00\",\"dateModified\":\"2026-09-01T13:52:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/\"},\"wordCount\":2349,\"publisher\":{\"@id\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/How-To-Transcribe-Genesys-Recordings-Automatically-scaled.jpg\",\"articleSection\":[\"Education\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/\",\"url\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/\",\"name\":\"How To Transcribe Genesys Recordings Automatically - Moving AI Forward\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/How-To-Transcribe-Genesys-Recordings-Automatically-scaled.jpg\",\"datePublished\":\"2026-09-01T11:30:10+00:00\",\"dateModified\":\"2026-09-01T13:52:30+00:00\",\"description\":\"Learn how to transcribe Genesys recordings automatically with AI. Explore native Genesys tools, Sonix, setup steps, AI analysis, security, and integrations.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/How-To-Transcribe-Genesys-Recordings-Automatically-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/How-To-Transcribe-Genesys-Recordings-Automatically-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Transcribe Genesys Recordings Automatically\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/transcribe-genesys-recordings-automatically\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How To Transcribe Genesys Recordings Automatically\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/#website\",\"url\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/\",\"name\":\"Sonix AI\",\"description\":\"Industry trends and enterprise solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/#organization\",\"name\":\"Sonix\",\"url\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Sonix-logo.webp\",\"contentUrl\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Sonix-logo.webp\",\"width\":310,\"height\":310,\"caption\":\"Sonix\"},\"image\":{\"@id\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/trysonix\\\/\",\"https:\\\/\\\/x.com\\\/trysonix\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sonix-inc\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@sonixai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sonixai.wpenginepowered.com\\\/#\\\/schema\\\/person\\\/7508f0c221b1e91520f0bf82e8f2ff37\",\"name\":\"David Nguyen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd9764668f128af42290ca959a4b172ff19655d1ab06daeedacd8ddef1b82b61?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd9764668f128af42290ca959a4b172ff19655d1ab06daeedacd8ddef1b82b61?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd9764668f128af42290ca959a4b172ff19655d1ab06daeedacd8ddef1b82b61?s=96&d=mm&r=g\",\"caption\":\"David Nguyen\"},\"url\":\"https:\\\/\\\/sonix.ai\\\/ai\\\/pt\\\/author\\\/davidatsonix\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como transcrever automaticamente grava\u00e7\u00f5es do Genesys - Impulsionando a IA","description":"Saiba como transcrever automaticamente as grava\u00e7\u00f5es da Genesys com IA. Explore as ferramentas nativas da Genesys, o Sonix, os passos de configura\u00e7\u00e3o, a an\u00e1lise por IA, a seguran\u00e7a e as integra\u00e7\u00f5es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sonix.ai\/ai\/pt\/transcrever-automaticamente-as-gravacoes-do-genesys\/","og_locale":"pt_PT","og_type":"article","og_title":"How To Transcribe Genesys Recordings Automatically - Moving AI Forward","og_description":"Learn how to transcribe Genesys recordings automatically with AI. Explore native Genesys tools, Sonix, setup steps, AI analysis, security, and integrations.","og_url":"https:\/\/sonix.ai\/ai\/pt\/transcrever-automaticamente-as-gravacoes-do-genesys\/","og_site_name":"Moving AI Forward","article_publisher":"https:\/\/www.facebook.com\/trysonix\/","article_published_time":"2026-09-01T11:30:10+00:00","article_modified_time":"2026-09-01T13:52:30+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/sonix.ai\/ai\/wp-content\/uploads\/2026\/09\/How-To-Transcribe-Genesys-Recordings-Automatically-scaled.jpg","type":"image\/jpeg"}],"author":"David Nguyen","twitter_card":"summary_large_image","twitter_creator":"@trysonix","twitter_site":"@trysonix","twitter_misc":{"Written by":"David Nguyen","Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/#article","isPartOf":{"@id":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/"},"author":{"name":"David Nguyen","@id":"https:\/\/sonixai.wpenginepowered.com\/#\/schema\/person\/7508f0c221b1e91520f0bf82e8f2ff37"},"headline":"How To Transcribe Genesys Recordings Automatically","datePublished":"2026-09-01T11:30:10+00:00","dateModified":"2026-09-01T13:52:30+00:00","mainEntityOfPage":{"@id":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/"},"wordCount":2349,"publisher":{"@id":"https:\/\/sonixai.wpenginepowered.com\/#organization"},"image":{"@id":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/#primaryimage"},"thumbnailUrl":"https:\/\/sonix.ai\/ai\/wp-content\/uploads\/2026\/09\/How-To-Transcribe-Genesys-Recordings-Automatically-scaled.jpg","articleSection":["Education"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/","url":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/","name":"Como transcrever automaticamente grava\u00e7\u00f5es do Genesys - Impulsionando a IA","isPartOf":{"@id":"https:\/\/sonixai.wpenginepowered.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/#primaryimage"},"image":{"@id":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/#primaryimage"},"thumbnailUrl":"https:\/\/sonix.ai\/ai\/wp-content\/uploads\/2026\/09\/How-To-Transcribe-Genesys-Recordings-Automatically-scaled.jpg","datePublished":"2026-09-01T11:30:10+00:00","dateModified":"2026-09-01T13:52:30+00:00","description":"Saiba como transcrever automaticamente as grava\u00e7\u00f5es da Genesys com IA. Explore as ferramentas nativas da Genesys, o Sonix, os passos de configura\u00e7\u00e3o, a an\u00e1lise por IA, a seguran\u00e7a e as integra\u00e7\u00f5es.","breadcrumb":{"@id":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/#primaryimage","url":"https:\/\/sonix.ai\/ai\/wp-content\/uploads\/2026\/09\/How-To-Transcribe-Genesys-Recordings-Automatically-scaled.jpg","contentUrl":"https:\/\/sonix.ai\/ai\/wp-content\/uploads\/2026\/09\/How-To-Transcribe-Genesys-Recordings-Automatically-scaled.jpg","width":2560,"height":1707,"caption":"Transcribe Genesys Recordings Automatically"},{"@type":"BreadcrumbList","@id":"https:\/\/sonix.ai\/ai\/transcribe-genesys-recordings-automatically\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sonixai.wpenginepowered.com\/"},{"@type":"ListItem","position":2,"name":"How To Transcribe Genesys Recordings Automatically"}]},{"@type":"WebSite","@id":"https:\/\/sonixai.wpenginepowered.com\/#website","url":"https:\/\/sonixai.wpenginepowered.com\/","name":"Sonix AI","description":"Tend\u00eancias do sector e solu\u00e7\u00f5es empresariais","publisher":{"@id":"https:\/\/sonixai.wpenginepowered.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sonixai.wpenginepowered.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/sonixai.wpenginepowered.com\/#organization","name":"Sonix","url":"https:\/\/sonixai.wpenginepowered.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/sonixai.wpenginepowered.com\/#\/schema\/logo\/image\/","url":"https:\/\/sonix.ai\/ai\/wp-content\/uploads\/2025\/05\/Sonix-logo.webp","contentUrl":"https:\/\/sonix.ai\/ai\/wp-content\/uploads\/2025\/05\/Sonix-logo.webp","width":310,"height":310,"caption":"Sonix"},"image":{"@id":"https:\/\/sonixai.wpenginepowered.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/trysonix\/","https:\/\/x.com\/trysonix","https:\/\/www.linkedin.com\/company\/sonix-inc\/","https:\/\/www.youtube.com\/@sonixai"]},{"@type":"Person","@id":"https:\/\/sonixai.wpenginepowered.com\/#\/schema\/person\/7508f0c221b1e91520f0bf82e8f2ff37","name":"David Nguyen","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/cd9764668f128af42290ca959a4b172ff19655d1ab06daeedacd8ddef1b82b61?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd9764668f128af42290ca959a4b172ff19655d1ab06daeedacd8ddef1b82b61?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd9764668f128af42290ca959a4b172ff19655d1ab06daeedacd8ddef1b82b61?s=96&d=mm&r=g","caption":"David Nguyen"},"url":"https:\/\/sonix.ai\/ai\/pt\/author\/davidatsonix\/"}]}},"featured_image_src":"https:\/\/sonix.ai\/ai\/wp-content\/uploads\/2026\/09\/How-To-Transcribe-Genesys-Recordings-Automatically-600x400.jpg","featured_image_src_square":"https:\/\/sonix.ai\/ai\/wp-content\/uploads\/2026\/09\/How-To-Transcribe-Genesys-Recordings-Automatically-600x600.jpg","author_info":{"display_name":"David Nguyen","author_link":"https:\/\/sonix.ai\/ai\/pt\/author\/davidatsonix\/"},"_links":{"self":[{"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/posts\/982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/comments?post=982"}],"version-history":[{"count":1,"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/posts\/982\/revisions"}],"predecessor-version":[{"id":984,"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/posts\/982\/revisions\/984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/media\/983"}],"wp:attachment":[{"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/media?parent=982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/categories?post=982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonix.ai\/ai\/pt\/wp-json\/wp\/v2\/tags?post=982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}